{"id":12251,"date":"2024-06-20T20:59:03","date_gmt":"2024-06-20T18:59:03","guid":{"rendered":"https:\/\/pavimentosarquiservi.com\/blog\/?p=12251"},"modified":"2024-06-21T13:47:36","modified_gmt":"2024-06-21T11:47:36","slug":"como-cortar-cesped-artificial","status":"publish","type":"post","link":"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/","title":{"rendered":"C\u00f3mo cortar c\u00e9sped artificial"},"content":{"rendered":"<p><a href=\"https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial.jpg\" rel=\"mfp\"><img decoding=\"async\" class=\"size-full wp-image-12253 aligncenter\" src=\"https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial.jpg\" alt=\"Como cortar cesped artificial\" width=\"640\" height=\"427\" title=\"\" srcset=\"https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial.jpg 640w, https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial-300x200.jpg 300w, https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial-450x300.jpg 450w, https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial-225x150.jpg 225w, https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial-20x13.jpg 20w, https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Como-cortar-cesped-artificial-144x96.jpg 144w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Un paso crucial en la instalaci\u00f3n del c\u00e9sped artificial, es el corte. Aunque puede parecer una tarea muy complicada, la realidad es que con los consejos y las directrices correctas es posible lograrlo con \u00e9xito.\u00a0 Si est\u00e1s interesado en aprender<em><strong> c\u00f3mo cortar c\u00e9sped artificial<\/strong><\/em>, no dejes de leer esta gu\u00eda, en la que te explicamos todo lo que necesitas saber.<\/p>\n<p><!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_84 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de Contenidos<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57f6dc75fc5\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57f6dc75fc5\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#%C2%BFPor_que_es_importante_cortar_el_cesped_artificial\" >\u00bfPor qu\u00e9 es importante cortar el c\u00e9sped artificial?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Herramientas_necesarias_para_cortar_el_cesped_artificial\" >Herramientas necesarias para cortar el c\u00e9sped artificial<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Pasos_previos_al_corte_del_Cesped_Artificial\" >Pasos previos al corte del C\u00e9sped Artificial<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Medicion_de_la_superficie\" >Medici\u00f3n de la superficie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Limpieza_y_preparacion_del_terreno\" >Limpieza y preparaci\u00f3n del terreno<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Planificacion_del_diseno_y_colocacion\" >Planificaci\u00f3n del dise\u00f1o y colocaci\u00f3n<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Proceso_de_corte_del_Cesped_Artificial\" >Proceso de corte del C\u00e9sped Artificial<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Extender_y_alinear_el_cesped\" >Extender y alinear el c\u00e9sped<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Marcar_los_obstaculos_y_perimetros\" >Marcar los obst\u00e1culos y per\u00edmetros<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Realizar_cortes_precisos_siguiendo_las_marcas\" >Realizar cortes precisos siguiendo las marcas<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Consejos_para_evitar_errores_comunes\" >Consejos para evitar errores comunes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Como_disimular_las_juntas\" >C\u00f3mo disimular las juntas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Tecnicas_para_uniones_perfectas\" >T\u00e9cnicas para uniones perfectas<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Mantenimiento_de_las_herramientas_de_corte\" >Mantenimiento de las herramientas de corte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#Preguntas_frecuentes_sobre_el_corte_del_Cesped_Artificial\" >Preguntas frecuentes sobre el corte del C\u00e9sped Artificial<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#%C2%BFEs_necesario_cortar_el_cesped_artificial_regularmente\" >\u00bfEs necesario cortar el c\u00e9sped artificial regularmente?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#%C2%BFQue_hacer_si_se_cometen_errores_en_el_corte\" >\u00bfQu\u00e9 hacer si se cometen errores en el corte?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-cortar-cesped-artificial\/#%C2%BFCuanto_cesped_extra_debo_comprar_para_imprevistos\" >\u00bfCu\u00e1nto c\u00e9sped extra debo comprar para imprevistos?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_es_importante_cortar_el_cesped_artificial\"><\/span>\u00bfPor qu\u00e9 es importante cortar el c\u00e9sped artificial?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Saber c\u00f3mo cortar el <a href=\"https:\/\/pavimentosarquiservi.com\/cesped\">c\u00e9sped artificial<\/a> de forma adecuada, es una manera de garantizar una instalaci\u00f3n m\u00e1s uniforme y con acabado m\u00e1s prolijo.<\/p>\n<p>Adem\u00e1s, cuando se corta de manera correcta, el resultado es un c\u00e9sped m\u00e1s atractivo y que se mantenga en perfectas condiciones a largo plazo.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Herramientas_necesarias_para_cortar_el_cesped_artificial\"><\/span>Herramientas necesarias para cortar el c\u00e9sped artificial<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ol>\n<li>C\u00fater industrial, con una hojilla de un grosor proporcional con el del c\u00e9sped.<\/li>\n<li>Tijeras grandes de jard\u00edn.<\/li>\n<li>Guantes y lentes de protecci\u00f3n.<\/li>\n<li>Cinta m\u00e9trica.<\/li>\n<li>Rotuladores, tiza o l\u00e1piz para hacer las marcas de los cortes por la parte posterior del rollo de c\u00e9sped artificial.<\/li>\n<li>Regla.<\/li>\n<li>Comp\u00e1s, en caso de necesitar cortar curvas.<\/li>\n<li>Cinta de uni\u00f3n para las juntas.<\/li>\n<\/ol>\n<h2><span class=\"ez-toc-section\" id=\"Pasos_previos_al_corte_del_Cesped_Artificial\"><\/span>Pasos previos al corte del C\u00e9sped Artificial<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para comenzar a cortar el c\u00e9sped artificial y lograr un buen resultado, es esencial tener a mano todas las herramientas y materiales necesarios. De esta forma podr\u00e1s trabajar de manera m\u00e1s r\u00e1pida y efectiva.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Medicion_de_la_superficie\"><\/span>Medici\u00f3n de la superficie<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Medir la superficie con cuidado y saber c\u00f3mo va a colocar el c\u00e9sped va a evitar que se desperdicie material y que la instalaci\u00f3n luzca m\u00e1s natural.\u00a0 Si tienes problemas con algunas zonas como las esquinas o los bordes, puedes medir dos veces antes de hacer los cortes, para estar seguro de que son las medidas exactas.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Limpieza_y_preparacion_del_terreno\"><\/span>Limpieza y preparaci\u00f3n del terreno<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Limpiar el terreno, eliminando hojas secas, ramas y cualquier otro residuo.<\/p>\n<p>Adicionalmente, debes asegurarte de que la <a href=\"https:\/\/pavimentosarquiservi.com\/blog\/superficies-recomendable-instalar-cesped-artificial\/\">superficie para la instalaci\u00f3n del c\u00e9sped artificial<\/a> sea uniforme. Si se trata de tierra natural hay que allanar el terreno, o si hay otro subsuelo, revisar si es necesario rellenar o aplanar en algunos puntos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Planificacion_del_diseno_y_colocacion\"><\/span>Planificaci\u00f3n del dise\u00f1o y colocaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es importante planificar la manera como se colocar\u00e1, estar seguro de que todas las piezas siguen la misma direcci\u00f3n de las cerdas y tambi\u00e9n si se va a seguir alg\u00fan dise\u00f1o o patr\u00f3n hay que tenerlo definido con anticipaci\u00f3n. Recuerda que <strong>no se puede ir pegando el c\u00e9sped artificial y luego ir contando el excedente<\/strong>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Proceso_de_corte_del_Cesped_Artificial\"><\/span><a href=\"https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Instalacion-de-cesped-con-obstaculos.jpg\" rel=\"mfp\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/pavimentosarquiservi.com\/blog\/wp-content\/uploads\/2024\/06\/Instalacion-de-cesped-con-obstaculos.jpg\" alt=\"\" width=\"468\" height=\"468\" title=\"\"><\/a>Proceso de corte del C\u00e9sped Artificial<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Extender_y_alinear_el_cesped\"><\/span>Extender y alinear el c\u00e9sped<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Lo siguiente es colocar los rollos de c\u00e9sped artificial, extendi\u00e9ndolos por toda la superficie a instalar. Se debe tener especial cuidado de que no queden arrugas o pliegues, as\u00ed como evitar que queden costuras innecesarias.<\/p>\n<p>Colocar el c\u00e9sped artificial sobre el terreno donde se va a instalar, te dar\u00e1 una idea m\u00e1s clara de c\u00f3mo encajar\u00e1 todo, una vez que est\u00e9 terminando el proceso.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Marcar_los_obstaculos_y_perimetros\"><\/span>Marcar los obst\u00e1culos y per\u00edmetros<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Si en al \u00e1rea de instalaci\u00f3n hay obst\u00e1culos, tales como \u00e1rboles, jardineras, desag\u00fces, adoquines, bordes, farolas, etc.; es indispensable marcar bien antes de hacer cualquier corte.<\/p>\n<p>Las marcas servir\u00e1 de gu\u00eda para realizar los cortes.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Realizar_cortes_precisos_siguiendo_las_marcas\"><\/span>Realizar cortes precisos siguiendo las marcas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El c\u00e9sped artificial se corta por la parte del reverso, por ello las marcas se deben realizar en la parte trasera del material, para poder hacer cortes precisos.<\/p>\n<p>Se debe cortar en l\u00edneas rectas para una mejor apariencia y para lograr uniones menos visibles. Para conseguir cortes rectos, puedes ayudarte con una regla grande o una tabla de madera para hacerlo lo m\u00e1s derecho y exacto posible. Adem\u00e1s, ser\u00e1 necesario tener las herramientas bien afiladas.<\/p>\n<p>Hay que recordar que un error en los cortes podr\u00eda hacer que pierdas mucho material.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Consejos_para_evitar_errores_comunes\"><\/span>Consejos para evitar errores comunes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Como_disimular_las_juntas\"><\/span>C\u00f3mo disimular las juntas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Una vez que tengas colocado el c\u00e9sped artificial, cortado, sobre la superficie de instalaci\u00f3n, justo debajo del \u00e1rea donde estar\u00e1n las uniones, se coloca una cinta de uni\u00f3n autoadhesiva para las juntas.<\/p>\n<p>Entonces, se pegan ambos extremos del c\u00e9sped y se adhieren, tomando en cuenta la direcci\u00f3n de las cerdas del c\u00e9sped para que luzca uniforme. Luego con un cepillo suave o con la mano se peinan las cerdas para que la uni\u00f3n no se note.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Tecnicas_para_uniones_perfectas\"><\/span>T\u00e9cnicas para uniones perfectas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Extiende los rollos de c\u00e9sped artificial 24 horas antes.<\/li>\n<li>La direcci\u00f3n de las fibras debe ser igual en toda la superficie.<\/li>\n<li>Cortar la banda de seguridad de aproximadamente 1 cm que trae cada rollo, de modo que las imperfecciones de f\u00e1brica o producidas al momento del transporte.<\/li>\n<li>La separaci\u00f3n ideal de la uni\u00f3n entre un rollo y otro debe ser de 0,5 cent\u00edmetros, para que no quede demasiado junto ni muy separado.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Mantenimiento_de_las_herramientas_de_corte\"><\/span>Mantenimiento de las herramientas de corte<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Las herramientas de corte bien afiladas son fundamentales para cortar bien el c\u00e9sped artificial, y lograr que quede instalado de forma correcta.\u00a0 Cuando se est\u00e9 cortando el c\u00e9sped artificial se deben inspeccionar las herramientas y sustituir las piezas da\u00f1adas o desgastadas.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Preguntas_frecuentes_sobre_el_corte_del_Cesped_Artificial\"><\/span>Preguntas frecuentes sobre el corte del C\u00e9sped Artificial<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFEs_necesario_cortar_el_cesped_artificial_regularmente\"><\/span>\u00bfEs necesario cortar el c\u00e9sped artificial regularmente?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>No.\u00a0 Una vez que el c\u00e9sped artificial ya est\u00e9 instalado, no ser\u00e1 necesario hacer otros cortes.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFQue_hacer_si_se_cometen_errores_en_el_corte\"><\/span>\u00bfQu\u00e9 hacer si se cometen errores en el corte?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En caso de hacer un corte errado, puedes optar por colocar un parche o reemplazar una secci\u00f3n, cortando el pedazo de c\u00e9sped mal cortado, y sustituyendo por otra pieza del tama\u00f1o exacto y peg\u00e1ndola con cinta adhesiva para uniones. Si el error resulta dif\u00edcil de manejar, otra opci\u00f3n es llamar a un equipo de profesionales para encontrar la mejor soluci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFCuanto_cesped_extra_debo_comprar_para_imprevistos\"><\/span>\u00bfCu\u00e1nto c\u00e9sped extra debo comprar para imprevistos?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Se recomienda comprar un diez por ciento m\u00e1s de c\u00e9sped artificial, en relaci\u00f3n con la cantidad de metros cuadrados de la superficie donde se va a instalar. De esta forma se garantiza que habr\u00e1 suficiente margen para los cortes, las juntas y el per\u00edmetro.<\/p>\n<p>Saber c\u00f3mo cortar el c\u00e9sped artificial de la mejor manera posible, la correcta instalaci\u00f3n y una buena <a href=\"https:\/\/pavimentosarquiservi.com\/blog\/como-limpiar-cesped-artificial\/\">limpieza y mantenimiento del c\u00e9sped<\/a> aseguran su durabilidad a largo plazo.\u00a0 Si tienes dudas sobre la compra de c\u00e9sped artificial puedes comunicarte con nuestro equipo de expertos y con gusto te ayudaremos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un paso crucial en la instalaci\u00f3n del c\u00e9sped artificial, es el corte. Aunque puede parecer una tarea muy complicada, la realidad es que con los consejos y las directrices correctas es posible lograrlo con \u00e9xito.\u00a0 Si est\u00e1s interesado en aprender c\u00f3mo cortar c\u00e9sped artificial, no dejes de leer esta gu\u00eda, en la que te explicamos&hellip;<\/p>\n","protected":false},"author":20,"featured_media":12253,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2309],"tags":[1474,2211],"thb-sponsors":[],"class_list":["post-12251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cesped-artificial","tag-cesped","tag-instalacion"],"_links":{"self":[{"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/posts\/12251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/comments?post=12251"}],"version-history":[{"count":4,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/posts\/12251\/revisions"}],"predecessor-version":[{"id":12257,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/posts\/12251\/revisions\/12257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/media\/12253"}],"wp:attachment":[{"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/media?parent=12251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/categories?post=12251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/tags?post=12251"},{"taxonomy":"thb-sponsors","embeddable":true,"href":"https:\/\/pavimentosarquiservi.com\/blog\/wp-json\/wp\/v2\/thb-sponsors?post=12251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}